{"id":2176,"date":"2024-04-12T17:10:57","date_gmt":"2024-04-12T20:10:57","guid":{"rendered":"https:\/\/electronicatotal.com.uy\/index.php\/producto\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\/"},"modified":"2026-08-13T16:35:01","modified_gmt":"2026-08-13T19:35:01","slug":"bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585","status":"publish","type":"product","link":"https:\/\/electronicatotal.com.uy\/index.php\/producto\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\/","title":{"rendered":"BisagraLenovoG585, Bisagra Derecha e Izquierda Lenovo G585, Model name:20137. Utilizadas en: G580 G580A G585"},"content":{"rendered":"<p>BisagraLenovoG585, Bisagra Derecha e Izquierda Lenovo G585, Model name:20137. Utilizadas en: G580 G580A G585<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BisagraLenovoG585, Bisagra Derecha e Izquierda Lenovo G585, Model name:20137. Utilizadas en: G580 G580A G585<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[33,109],"product_tag":[],"class_list":["post-2176","product","type-product","status-publish","product_cat-componentes","product_cat-varios","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BisagraLenovoG585, Bisagra Derecha e Izquierda Lenovo G585, Model name:20137. Utilizadas en: G580 G580A G585 - Electr\u00f3nica Total<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/electronicatotal.com.uy\/index.php\/producto\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BisagraLenovoG585, Bisagra Derecha e Izquierda Lenovo G585, Model name:20137. Utilizadas en: G580 G580A G585 - Electr\u00f3nica Total\" \/>\n<meta property=\"og:description\" content=\"BisagraLenovoG585, Bisagra Derecha e Izquierda Lenovo G585, Model name:20137. Utilizadas en: G580 G580A G585\" \/>\n<meta property=\"og:url\" content=\"https:\/\/electronicatotal.com.uy\/index.php\/producto\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\/\" \/>\n<meta property=\"og:site_name\" content=\"Electr\u00f3nica Total\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/electronicaTotal.com.uy\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-13T19:35:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/electronicatotal.com.uy\/wp-content\/uploads\/2024\/03\/ElectronicaTotal_Logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/electronicatotal.com.uy\\\/index.php\\\/producto\\\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\\\/\",\"url\":\"https:\\\/\\\/electronicatotal.com.uy\\\/index.php\\\/producto\\\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\\\/\",\"name\":\"BisagraLenovoG585, Bisagra Derecha e Izquierda Lenovo G585, Model name:20137. Utilizadas en: G580 G580A G585 - Electr\u00f3nica Total\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/electronicatotal.com.uy\\\/#website\"},\"datePublished\":\"2024-04-12T20:10:57+00:00\",\"dateModified\":\"2026-08-13T19:35:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/electronicatotal.com.uy\\\/index.php\\\/producto\\\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/electronicatotal.com.uy\\\/index.php\\\/producto\\\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/electronicatotal.com.uy\\\/index.php\\\/producto\\\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/electronicatotal.com.uy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/electronicatotal.com.uy\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BisagraLenovoG585, Bisagra Derecha e Izquierda Lenovo G585, Model name:20137. Utilizadas en: G580 G580A G585\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/electronicatotal.com.uy\\\/#website\",\"url\":\"https:\\\/\\\/electronicatotal.com.uy\\\/\",\"name\":\"Electr\u00f3nicaTotal\",\"description\":\"Venta de componentes electr\u00f3nicos en Montevideo Uruguay\",\"publisher\":{\"@id\":\"https:\\\/\\\/electronicatotal.com.uy\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/electronicatotal.com.uy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/electronicatotal.com.uy\\\/#organization\",\"name\":\"Electr\u00f3nica Total\",\"url\":\"https:\\\/\\\/electronicatotal.com.uy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/electronicatotal.com.uy\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/electronicatotal.com.uy\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ElectronicaTotal_Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/electronicatotal.com.uy\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ElectronicaTotal_Logo.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Electr\u00f3nica Total\"},\"image\":{\"@id\":\"https:\\\/\\\/electronicatotal.com.uy\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/electronicaTotal.com.uy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BisagraLenovoG585, Bisagra Derecha e Izquierda Lenovo G585, Model name:20137. Utilizadas en: G580 G580A G585 - Electr\u00f3nica Total","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/electronicatotal.com.uy\/index.php\/producto\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\/","og_locale":"es_ES","og_type":"article","og_title":"BisagraLenovoG585, Bisagra Derecha e Izquierda Lenovo G585, Model name:20137. Utilizadas en: G580 G580A G585 - Electr\u00f3nica Total","og_description":"BisagraLenovoG585, Bisagra Derecha e Izquierda Lenovo G585, Model name:20137. Utilizadas en: G580 G580A G585","og_url":"https:\/\/electronicatotal.com.uy\/index.php\/producto\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\/","og_site_name":"Electr\u00f3nica Total","article_publisher":"https:\/\/www.facebook.com\/electronicaTotal.com.uy\/","article_modified_time":"2026-08-13T19:35:01+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/electronicatotal.com.uy\/wp-content\/uploads\/2024\/03\/ElectronicaTotal_Logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/electronicatotal.com.uy\/index.php\/producto\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\/","url":"https:\/\/electronicatotal.com.uy\/index.php\/producto\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\/","name":"BisagraLenovoG585, Bisagra Derecha e Izquierda Lenovo G585, Model name:20137. Utilizadas en: G580 G580A G585 - Electr\u00f3nica Total","isPartOf":{"@id":"https:\/\/electronicatotal.com.uy\/#website"},"datePublished":"2024-04-12T20:10:57+00:00","dateModified":"2026-08-13T19:35:01+00:00","breadcrumb":{"@id":"https:\/\/electronicatotal.com.uy\/index.php\/producto\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/electronicatotal.com.uy\/index.php\/producto\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/electronicatotal.com.uy\/index.php\/producto\/bisagralenovog585-bisagra-derecha-e-izquierda-lenovo-g585-model-name20137-utilizadas-en-g580-g580a-g585\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/electronicatotal.com.uy\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/electronicatotal.com.uy\/"},{"@type":"ListItem","position":3,"name":"BisagraLenovoG585, Bisagra Derecha e Izquierda Lenovo G585, Model name:20137. Utilizadas en: G580 G580A G585"}]},{"@type":"WebSite","@id":"https:\/\/electronicatotal.com.uy\/#website","url":"https:\/\/electronicatotal.com.uy\/","name":"Electr\u00f3nicaTotal","description":"Venta de componentes electr\u00f3nicos en Montevideo Uruguay","publisher":{"@id":"https:\/\/electronicatotal.com.uy\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/electronicatotal.com.uy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/electronicatotal.com.uy\/#organization","name":"Electr\u00f3nica Total","url":"https:\/\/electronicatotal.com.uy\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/electronicatotal.com.uy\/#\/schema\/logo\/image\/","url":"https:\/\/electronicatotal.com.uy\/wp-content\/uploads\/2024\/03\/ElectronicaTotal_Logo.jpg","contentUrl":"https:\/\/electronicatotal.com.uy\/wp-content\/uploads\/2024\/03\/ElectronicaTotal_Logo.jpg","width":1280,"height":720,"caption":"Electr\u00f3nica Total"},"image":{"@id":"https:\/\/electronicatotal.com.uy\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/electronicaTotal.com.uy\/"]}]}},"_links":{"self":[{"href":"https:\/\/electronicatotal.com.uy\/index.php\/wp-json\/wp\/v2\/product\/2176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/electronicatotal.com.uy\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/electronicatotal.com.uy\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/electronicatotal.com.uy\/index.php\/wp-json\/wp\/v2\/media?parent=2176"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/electronicatotal.com.uy\/index.php\/wp-json\/wp\/v2\/product_brand?post=2176"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/electronicatotal.com.uy\/index.php\/wp-json\/wp\/v2\/product_cat?post=2176"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/electronicatotal.com.uy\/index.php\/wp-json\/wp\/v2\/product_tag?post=2176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}